{"id":5398,"date":"2023-06-18T13:27:45","date_gmt":"2023-06-18T13:27:45","guid":{"rendered":"https:\/\/fkv.it\/strumentazionedalaboratorio\/?p=5398"},"modified":"2024-03-07T15:38:33","modified_gmt":"2024-03-07T15:38:33","slug":"coordinate-colororimetriche","status":"publish","type":"post","link":"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/","title":{"rendered":"Determinazione delle coordinate colorimetriche"},"content":{"rendered":"\n<p>Il metodo pi\u00f9 semplice per seguire la <strong>determinazione delle coordinate colorimetriche senza alterare il campione<\/strong> \u00e8 utilizzare la <a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/glossario\/uv-visibile\/\">spettrofotometria UV-Vis<\/a> con un ampio comparto per l\u2019installazione degli accessori.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/07\/Specord_210_PLUS_alpha-edited.jpg\" alt=\"spettrofotometro uv-vis specord plus\" class=\"wp-image-4174\" width=\"332\" height=\"187\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/07\/Specord_210_PLUS_alpha-edited.jpg 660w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/07\/Specord_210_PLUS_alpha-edited-300x169.jpg 300w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/><\/figure><\/div>\n\n\n\n<p>Gli spettrofotometri a doppio raggio <a href=\"https:\/\/fkv.it\/prodotti\/analisi-chimiche\/analisi-uv-vis\/specord-50-plus-%E2%80%93-spettrofotometro-a-doppio-raggio\">Specord 50 Plus<\/a> e <a href=\"https:\/\/fkv.it\/prodotti\/analisi-chimiche\/analisi-uv-vis\/specord-200p-%E2%80%93-spettrofotometro-a-doppio-raggio-con-fenditura-fissa\">Specord 210 Plus<\/a> sono le soluzioni di Analytik Jena che permettono di determinare in modo accurato le <strong>coordinate colorimetriche<\/strong> di un campione senza alterarlo.<\/p>\n\n\n\n<p>Entrambi gli strumenti dispongono di un ampio comparto (364 x 185 x 200 mm) nel quale possono essere alloggiati diversi accessori, inclusi caroselli multicuvetta, rack termostatati e sistemi per la determinazione del colore. Due accessori sono adatti per queste determinazioni, entrambi<strong> non necessitano di tagliare il tessuto in una particolare forma <\/strong>per essere analizzati, inoltre l\u2019analisi non altera il campione:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/NL06_Fig1-AccMisRif.png\" alt=\"\" class=\"wp-image-5399\" width=\"666\" height=\"457\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/NL06_Fig1-AccMisRif.png 875w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/NL06_Fig1-AccMisRif-300x206.png 300w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/NL06_Fig1-AccMisRif-768x528.png 768w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><\/figure><\/div>\n\n\n\n<h3>Accessorio per la misura della riflettanza ad angoli variabili<\/h3>\n\n\n\n<p>Con questo accessorio \u00e8 possibile <strong>determinare la riflettanza di un campione solido ad angoli di riflessione variabili tra 11\u00b0 e 60\u00b0<\/strong>. Il campione di tessuto pu\u00f2 essere ripiegato e inserito nella parte superiore dell\u2019accessorio (nella foto \u00e8 il tessuto bianco fermato da due molle).<\/p>\n\n\n\n<h3>Sfera di integrazione<\/h3>\n\n\n\n<p>Con questo accessorio \u00e8 possibile determinare la diffusione di un campione solido o liquido sia in trasmittanza sia in riflettanza. Il campione di tessuto pu\u00f2 essere ripiegato e inserito nella parte destra dell\u2019accessorio (nella foto la sfera di integrazione \u00e8 inserita nello spettrofotometro, il campione rosso \u00e8 fermato da una molla).<\/p>\n\n\n\n<p>Con gli <strong>spettrofotometri della serie Specord Plus<\/strong> e con gli accessori Analytik Jena dedicati alla colorimetria \u00e8 possibile effettuare <strong>determinazioni accurate delle coordinate colorimetriche su tessuti, oggetti solidi, materiali polverosi, liquidi<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il metodo pi\u00f9 semplice per seguire la determinazione delle coordinate colorimetriche senza alterare il campione \u00e8 utilizzare la spettrofotometria UV-Vis.<\/p>\n","protected":false},"author":3,"featured_media":5396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[336],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Determinazione delle coordinate colorimetriche - FKV<\/title>\n<meta name=\"description\" content=\"Il metodo pi\u00f9 semplice per seguire la determinazione delle coordinate colorimetriche senza alterare il campione \u00e8 utilizzare la spettrofotometria UV-Vis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Determinazione delle coordinate colorimetriche - FKV\" \/>\n<meta property=\"og:description\" content=\"Il metodo pi\u00f9 semplice per seguire la determinazione delle coordinate colorimetriche senza alterare il campione \u00e8 utilizzare la spettrofotometria UV-Vis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/\" \/>\n<meta property=\"og:site_name\" content=\"FKV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/FKV-SRL\/193967133985052\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-18T13:27:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T15:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/FKV_Banner-Conciario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\",\"name\":\"FKV - Strumenti per Laboratorio\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/FKV-SRL\/193967133985052\",\"https:\/\/www.linkedin.com\/company\/fkv-srl\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2019\/09\/logo_FKV.png\",\"width\":150,\"height\":86,\"caption\":\"FKV - Strumenti per Laboratorio\"},\"image\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#website\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/\",\"name\":\"FKV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2023\/06\/FKV_Banner-Conciario.jpg\",\"width\":1024,\"height\":536},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#webpage\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/\",\"name\":\"Determinazione delle coordinate colorimetriche - FKV\",\"isPartOf\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#primaryimage\"},\"datePublished\":\"2023-06-18T13:27:45+00:00\",\"dateModified\":\"2024-03-07T15:38:33+00:00\",\"description\":\"Il metodo pi\\u00f9 semplice per seguire la determinazione delle coordinate colorimetriche senza alterare il campione \\u00e8 utilizzare la spettrofotometria UV-Vis.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#\/schema\/person\/c5c2ae75376c51805613adcb1ea111d8\"},\"headline\":\"Determinazione delle coordinate colorimetriche\",\"datePublished\":\"2023-06-18T13:27:45+00:00\",\"dateModified\":\"2024-03-07T15:38:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\"},\"image\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2023\/06\/18\/coordinate-colororimetriche\/#primaryimage\"},\"keywords\":\"UV-VIS\",\"articleSection\":\"Chimico\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#\/schema\/person\/c5c2ae75376c51805613adcb1ea111d8\",\"name\":\"Leila\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5164a159b0f29b16a260987c7c6188c7?s=96&d=mm&r=g\",\"caption\":\"Leila\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/5398"}],"collection":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/comments?post=5398"}],"version-history":[{"count":3,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/5398\/revisions"}],"predecessor-version":[{"id":6385,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/5398\/revisions\/6385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/media\/5396"}],"wp:attachment":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/media?parent=5398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/categories?post=5398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/tags?post=5398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}