{"id":4295,"date":"2022-09-27T08:53:11","date_gmt":"2022-09-27T08:53:11","guid":{"rendered":"https:\/\/fkv.it\/strumentazionedalaboratorio\/?p=4295"},"modified":"2023-10-16T12:58:44","modified_gmt":"2023-10-16T12:58:44","slug":"impurezze-rame-puro","status":"publish","type":"post","link":"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/","title":{"rendered":"Determinazione delle impurezze nel rame puro"},"content":{"rendered":"\n<p>Il rame ad elevata purezza \u00e8 un<strong> eccellente conduttore di elettricit\u00e0<\/strong> ed \u00e8 comunemente utilizzato nelle <strong>apparecchiature elettriche<\/strong>. Alcune <strong>impurezze<\/strong> per\u00f2 possono interferire con le performance del materiale e ridurne la conducibilit\u00e0, anche se a bassa concentrazione. \u00a0I cavi elettrici sono realizzati con rame ad elevata purezza proprio perch\u00e9 devono trasportare l\u2019elettricit\u00e0 per molti chilometri attraverso linee di trasmissione ad alta tensione.<\/p>\n\n\n\n<h2>Il rame puro<\/h2>\n\n\n\n<p>Le <strong>caratteristiche del rame puro<\/strong> sono alta duttilit\u00e0, elevata resistenza agli urti, buona resistenza allo scorrimento ed elevata conducibilit\u00e0 termica ed elettrica.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-808x1024.jpg\" alt=\"icp-ms\" class=\"wp-image-1864\" width=\"388\" height=\"492\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-808x1024.jpg 808w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-237x300.jpg 237w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-768x973.jpg 768w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-1213x1536.jpg 1213w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-1617x2048.jpg 1617w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2020\/10\/PQMS-scaled.jpg 2021w\" sizes=\"(max-width: 388px) 100vw, 388px\" \/><\/figure><\/div>\n\n\n\n<p>Il rame ad alta purezza viene prodotto tramite elettrolisi, dove rame anodico meno puro, derivato dalla fusione di minerali di rame, \u00e8 ridotto e produce rame puro al 99,99%.<\/p>\n\n\n\n<p>In questo materiale estremamente puro le <strong>concentrazioni di impurezze sono molto basse<\/strong>, ed \u00e8 quindi necessario lavorare con una tecnica molto sensibile come l\u2019<a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/glossario\/icp-massa\/\">ICP-MS<\/a>. <a href=\"https:\/\/fkv.it\/prodotti\/analisi-chimiche\/analisi-icp-oes-icp-ms\/plasmaquant-ms\">PlasmaQuant MS Elite<\/a> ad alta sensibilit\u00e0 raggiunge oltre 1,5 milioni di conteggi al secondo per ppb sull&#8217;isotopo 115 dell\u2019Indio ed \u00e8 lo strumento pi\u00f9 adatto per campioni di rame metallico ad alta purezza e materiali di riferimento standard.<\/p>\n\n\n\n<h2><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Determinazione delle impurezze<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> del rame<\/h2>\n\n\n\n<p>In base alle potenziali interferenze della matrice su determinati rapporti massa\/carica sono stati analizzati alcuni isotopi, utilizzando gas di collisione e di reazione tramite la <a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/01\/19\/come-risolvere-le-interferenze-icp-ms-con-utilizzo-del-sistema-icrc\/\">tecnologia iCRC<\/a> . Tre tipologie di condizioni sono state utilizzate: con utilizzo di H2, di He e non utilizzando alcun gas addizionale. Le condizioni operative utilizzate sono riportate in <em>Tabella 1<\/em>, mentre in <em>Tabella 2<\/em> vengono riportate le diverse interferenze nei vari metalli e i gas utilizzati con la tecnica iCRC.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1.jpg\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1-774x1024.jpg\" alt=\"\" class=\"wp-image-4314\" width=\"442\" height=\"584\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1-774x1024.jpg 774w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1-227x300.jpg 227w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1-768x1016.jpg 768w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-1.jpg 884w\" sizes=\"(max-width: 442px) 100vw, 442px\" \/><\/a><figcaption><strong><em>Tabella 1<\/em><\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p>I risultati dei metalli analizzati su tre campioni di rame metallico e un materiale di riferimento di rame puro sono elencati nella tabella 3. Il recupero per ciascun analita nel materiale di riferimento BAM M382 non si \u00e8 mai discostato pi\u00f9 del \u00b110 % dal valore certificato, mentre la deviazione standard relativa delle misure del campione \u00e8 sempre stato inferiore al 5 %, dimostrando la robustezza del metodo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2.jpg\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2-1024x448.jpg\" alt=\"\" class=\"wp-image-4315\" width=\"553\" height=\"241\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2-1024x448.jpg 1024w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2-300x131.jpg 300w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2-768x336.jpg 768w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/TABELLA-2.jpg 1298w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><figcaption><em><strong>Tabella 2<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>\u00c8 molto interessante vedere come il Plasma Quant MS ELlite sia performante con un eccellente recupero osservato su 66Zn, un isotopo direttamente adiacente all&#8217;intenso segnale 65Cu risultante dall\u2019elevato contenuto di rame nella matrice.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3.jpg\"><img loading=\"lazy\" src=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3-1024x682.jpg\" alt=\"\" class=\"wp-image-4316\" width=\"561\" height=\"373\" srcset=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3-1024x682.jpg 1024w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3-300x200.jpg 300w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3-768x511.jpg 768w, https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/Tabella-3.jpg 1513w\" sizes=\"(max-width: 561px) 100vw, 561px\" \/><\/a><figcaption><em><strong>Tabella 3<\/strong><\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Di particolare importanza \u00e8 che tutti i metalli analizzati in questa matrice ad alto contenuto di rame sono state analizzati in meno di 3 minuti, senza interferenze e utilizzando solo la met\u00e0 del gas argon di altri sistemi. Questa capacit\u00e0 riduce notevolmente i tempi analitici ed il risultato di un nuovo e innovativo design del generatore di radiofrequenza (RF) Eco Plasma disponibile sulla serie PlasmaQuant MS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il rame ad elevata purezza \u00e8 un eccellente conduttore di elettricit\u00e0 ed \u00e8 comunemente utilizzato nelle apparecchiature elettriche. Alcune impurezze per\u00f2 possono interferire con il materiale.<\/p>\n","protected":false},"author":3,"featured_media":4313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[440],"tags":[246],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Determinazione delle impurezze nel rame puro - FKV<\/title>\n<meta name=\"description\" content=\"Il rame ad elevata purezza \u00e8 un eccellente conduttore di elettricit\u00e0 ed \u00e8 comunemente utilizzato nelle apparecchiature elettriche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Determinazione delle impurezze nel rame puro - FKV\" \/>\n<meta property=\"og:description\" content=\"Il rame ad elevata purezza \u00e8 un eccellente conduttore di elettricit\u00e0 ed \u00e8 comunemente utilizzato nelle apparecchiature elettriche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/\" \/>\n<meta property=\"og:site_name\" content=\"FKV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/FKV-SRL\/193967133985052\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-27T08:53:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-16T12:58:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/elettronica_Ottobre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\",\"name\":\"FKV - Strumenti per Laboratorio\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/FKV-SRL\/193967133985052\",\"https:\/\/www.linkedin.com\/company\/fkv-srl\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2019\/09\/logo_FKV.png\",\"width\":150,\"height\":86,\"caption\":\"FKV - Strumenti per Laboratorio\"},\"image\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#website\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/\",\"name\":\"FKV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-content\/uploads\/2022\/09\/elettronica_Ottobre.jpg\",\"width\":1024,\"height\":536,\"caption\":\"Close-up view of a modern GPU card with circuit and connections\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#webpage\",\"url\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/\",\"name\":\"Determinazione delle impurezze nel rame puro - FKV\",\"isPartOf\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#primaryimage\"},\"datePublished\":\"2022-09-27T08:53:11+00:00\",\"dateModified\":\"2023-10-16T12:58:44+00:00\",\"description\":\"Il rame ad elevata purezza \\u00e8 un eccellente conduttore di elettricit\\u00e0 ed \\u00e8 comunemente utilizzato nelle apparecchiature elettriche.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#\/schema\/person\/c5c2ae75376c51805613adcb1ea111d8\"},\"headline\":\"Determinazione delle impurezze nel rame puro\",\"datePublished\":\"2022-09-27T08:53:11+00:00\",\"dateModified\":\"2023-10-16T12:58:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#organization\"},\"image\":{\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/2022\/09\/27\/impurezze-rame-puro\/#primaryimage\"},\"keywords\":\"ICP-MS\",\"articleSection\":\"Elettronico\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#\/schema\/person\/c5c2ae75376c51805613adcb1ea111d8\",\"name\":\"Leila\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fkv.it\/strumentazionedalaboratorio\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5164a159b0f29b16a260987c7c6188c7?s=96&d=mm&r=g\",\"caption\":\"Leila\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/4295"}],"collection":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/comments?post=4295"}],"version-history":[{"count":3,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/4295\/revisions"}],"predecessor-version":[{"id":4782,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/posts\/4295\/revisions\/4782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/media\/4313"}],"wp:attachment":[{"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/media?parent=4295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/categories?post=4295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fkv.it\/strumentazionedalaboratorio\/wp-json\/wp\/v2\/tags?post=4295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}